{"id":780,"date":"2011-07-27T11:54:21","date_gmt":"2011-07-27T09:54:21","guid":{"rendered":"http:\/\/www.hahnzog.de\/organisationsberatung\/?p=780"},"modified":"2014-03-14T11:52:08","modified_gmt":"2014-03-14T10:52:08","slug":"sozialpsychologie-soziale-interaktion","status":"publish","type":"post","link":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion","title":{"rendered":"Sozialpsychologie: Soziale Interaktion"},"content":{"rendered":"<p>Sie k\u00f6nnen sich diesen Artikel zum Nachlesen und Weiterverarbeiten auch als PDF herunterladen:<\/p>\n<p>&nbsp;<\/p>\n<table style=\"width: 683px;\" border=\"0\">\n<tbody>\n<tr>\n<td align=\"center\" valign=\"middle\"><a title=\"Prof. Dr. Simon Hahnzog - Sozialpsychologie: Interaktion\" href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2014\/03\/hahnzog-organisationsberatung_Sozialpsychologie-Interaktion.pdf\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-790\" title=\"hahnzog_organisationsberatung_Soziale Interaktion_Titel_blau\" alt=\"\" src=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg\" width=\"141\" height=\"100\" srcset=\"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg 141w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-400x282.jpg 400w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau.jpg 701w\" sizes=\"auto, (max-width: 141px) 100vw, 141px\" \/><\/a><\/td>\n<td align=\"left\" valign=\"bottom\"><a title=\"Prof. Dr. Simon Hahnzog - Sozialpsychologie: Interaktion\" href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2014\/03\/hahnzog-organisationsberatung_Sozialpsychologie-Interaktion.pdf\" target=\"_blank\">Prof. Dr. Simon Hahnzog:<br \/>\nSozialpsychologie &#8211; Soziale Interaktion<br \/>\nherunterladen<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><a title=\"Lexikon\" href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/lexikon\"><br \/>\n<\/a><\/p>\n<p><a title=\"Lexikon\" href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/lexikon\">Zur\u00fcck zur \u00dcbersicht<\/a> oder Artikel online lesen:<\/p>\n<p>&nbsp;<\/p>\n<h3>Prof. Dr. Simon Hahnzog &#8211; Ausgew\u00e4hlte Aspekte der Sozialpsychologie:<\/h3>\n<h1>Soziale Interaktion<\/h1>\n<h4>Inhalts\u00fcbersicht<\/h4>\n<ol>\n<li><strong><\/strong>Aggressives Verhalten<\/li>\n<li>Prosoziales Verhalten<\/li>\n<li>Interpersonale Attraktion und intime Beziehungen<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2>1. Aggressives Verhalten<\/h2>\n<p>Definition &#8211; Baron &amp; Richardson (1994):<\/p>\n<p>\u201eAggression ist jede Form von Verhalten, das darauf abzielt, einem anderen Lebewesen zu schaden oder es zu verletzen, wobei dieses Lebewesen motiviert ist, eine solche Behandlung zu vermeiden.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Konsequenzen:<\/p>\n<ul>\n<li>Aggression ist durch die ihr zugrunde gelegte <strong>Motivation<\/strong> <em>nicht<\/em> durch die Konsequenzen definiert.<\/li>\n<li>Notwendige Voraussetzung ist das <strong>Wissen<\/strong> darum, dass das gezeigte Verhalten sch\u00e4digen kann. Ansonsten basiert das Verhalten und die bewirkte Sch\u00e4digung auf Versehen, Fahrl\u00e4ssigkeit oder Unf\u00e4higkeit.<\/li>\n<li>Es handelt sich nicht um Aggression, wenn die Sch\u00e4digung auf Wunsch der gesch\u00e4digten Person ausgef\u00fchrt wurde (<strong>Perspektivendivergenz<\/strong>).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Unterkategorien:<\/p>\n<ul>\n<li>k\u00f6rperliche vs. verbale,<\/li>\n<li>spontane vs. reaktive,<\/li>\n<li>individuelle vs. intergruppale,<\/li>\n<li>instrumentelle vs. feindselige Aggression<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Funktionalit\u00e4t:<\/p>\n<ul>\n<li>soziale Identit\u00e4t und Sicherung des Selbstwerts<\/li>\n<li>Soziale Anpassung und Anerkennung<\/li>\n<li>Erlangen knapper G\u00fcter<\/li>\n<li>Sch\u00e4digung<\/li>\n<li>Evolution\u00e4rer Erfolg<\/li>\n<li>Verteidigung, Beseitigung aversiver Ereignisse<\/li>\n<\/ul>\n<h3><strong>Entstehung<\/strong><\/h3>\n<h4>\u00a0a)\u00a0\u00a0\u00a0 Philosophische Theorien zum Menschenbild:<\/h4>\n<ul>\n<li>\u00a0<strong>Nicollo Macchiavelli (1469 \u2013 1527)<\/strong>:<br \/>\nDer Mensch ist von Natur aus schlecht. Zugleich hat er jedoch als zentrale Triebfeder das Streben nach mehr und kann daher sozialisiert werden.<\/li>\n<li><strong>Thomas Hobbes (1588 \u2013 1679)<\/strong>:<br \/>\n\u201eHomo homini lupus\u201c \u2013 Der Mensch ist dem Menschen ein Wolf \u2013 daher kann ein friedliches gemeinsames Zusammenleben nur durch Gesellschaftsvertr\u00e4ge gesichert werden.<\/li>\n<li><strong>John Locke (1632 \u2013 1704)<\/strong>:<br \/>\nDer Mensch ist getrieben von Egoismus, Leidenschaft und Rachsucht.<\/li>\n<li><strong>Jean-Jaques Rousseau (1712 \u2013 1778)<\/strong>:<br \/>\nDer Mensch ist von sich aus gut und wird erst durch Erziehung ver\u00e4ndert.<\/li>\n<li><strong>Sigmund Freud (1856 \u2013 1939)<\/strong>:<br \/>\nZwei Triebe als ambivalente Gegenst\u00fccke\u00a0 des Verhaltens: Eros vs. Thanatos<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>b)\u00a0\u00a0\u00a0 Biologische Theorien:<\/h4>\n<ul>\n<li><strong>Verhaltensforschung<\/strong>:<br \/>\n\u201eDampfkesselmodell\u201c (K. Lorenz) = Aggression entsteht aus der Summe aggressiver Energie, die durch einen externen Reiz hervorbricht.<br \/>\nPsychologisch widerlegt (z.B. mehrfache Aggression, etc.)<\/li>\n<li><strong>Genetik<\/strong>:<br \/>\nGenetischer Einfluss vorhanden, jedoch geringer als Umwelteinfl\u00fcsse<\/li>\n<li><strong>Hormonelle Einfl\u00fcsse<\/strong>:<br \/>\nSowohl <strong>Testosteron<\/strong> als auch <strong>Cortisol <\/strong>zeigen keine eindeutigen, universellen Einfl\u00fcsse auf aggressives Verhalten.<\/li>\n<li><strong>Physiologische Einfl\u00fcsse<\/strong>:<br \/>\nSubstanzen wie Alkohol beg\u00fcnstigen aggressive Verhaltensweisen (Selbstaufmerksamkeit und Situationsbeurteilung werden beeintr\u00e4chtigt).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>c)\u00a0\u00a0\u00a0 Psychologische Theorien (Auswahl):<\/h4>\n<ul>\n<li><em>Frustrations-Aggressions-Hypothese<\/em> (Miller et al. 1939)<strong><br \/>\nFrustration<\/strong> (Blockierung einer zielgerichteten Aktivit\u00e4t) l\u00f6st verschiedene Reaktionen aus, u.a. Aggression. Ob Aggression oder andere Alternativen die Frustrationsreaktion darstellen, h\u00e4ngt von Person- und Umweltvariablen ab, z.B. Flucht- oder Erstarrungsreaktion (\u201efight, flight oder freeze\u201c).<br \/>\nAllerdings: Aggression ist dominante Reaktion auf Frustration.Kann die Frustrationsquelle nicht erreicht werden, so kann es zu einer <strong>Aggressionsverschiebung<\/strong> kommen, die sich gegen eine leichter zug\u00e4ngliche oder weniger bedrohliche Person richtet (Zielsubstitution) oder auf eher indirekte Art ge\u00e4u\u00dfert wird (Reaktionssubstitution).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><em>Theorie der aggressiven Hinweisreize<\/em>, \u201eSituative Cues\u201c (Berkowitz 1967)<br \/>\nBeeinflusst wird die aggressive Reaktion u.a. von <strong>aggressiven Hinweisreizen &#8211; <\/strong>Waffeneffekt (Berkowitz et al. 1967): Zuvor frustrierte Vpn, reagierten aggressiver, wenn neben ihnen eine Pistole lag, als Vpn der KG, neben denen ein Federballschl\u00e4ger lag.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><em>operante Konditionierung<\/em>(Skinner 1948)Definition und Abgrenzung:<br \/>\nBeim \u201e<strong>instrumentellen Lernen<\/strong>\u201c oder \u201e<strong>Operanten Konditionieren<\/strong>\u201c werden Lernprozesse beschrieben, bei denen die Ereignisse von der Ausf\u00fchrung einer Aktion abh\u00e4ngen. Im Unterschied zum Klassischen Konditionieren, bei dem der US unabh\u00e4ngig von der CR auftritt.<br \/>\nHier wird S-R-Beziehung statt S-S-Beziehung gelernt!<strong>Gesetz des Effekts <\/strong>(Edward L. Thorndike 1898):<br \/>\nThorndike untersuchte an Katzen, wie schnell sie sich aus K\u00e4figen (\u201epuzzlebox\u201c) befreien konnten. Das Lernen basiert hierbei auf dem Prozess des \u201etrial and error\u201c. Die Befreiungsversuche wurden immer k\u00fcrzer, daraus folgerte Thorndike:<br \/>\nFolgt auf ein Verhalten eine befriedigende Konsequenz, so erh\u00f6ht sich die Auftretenswahrscheinlichkeit dieses erfolgreichen (verst\u00e4rkten) Verhaltens.Verst\u00e4rkung<strong><br \/>\nfestigt<\/strong> die Assoziation zwischen Verhalten und KonsequenzL\u00f6schung<strong><br \/>\nschw\u00e4cht<\/strong> diese AssoziationBestrafungunterdr\u00fcckt nur das Auftreten des Verhaltens (die <strong>Performanz<\/strong>), die <strong>Kompetenz<\/strong> (die F\u00e4higkeit, im Prinzip das Verhalten zu zeigen) bleibt bestehen. F\u00e4llt die Bestrafung weg, tritt das zuvor gezeigte Verhalten schnell wieder auf.<br \/>\nBestrafung ist keine gute Methode der Verhaltenskontrolle.<br \/>\nWill man unerw\u00fcnschtes Verhalten eliminieren muss man L\u00f6schungsbedingungen herstellen. Au\u00dferdem die Gefahr der klassischen Konditionierung negativer Emotionen (Wut, Hass, Schmerz, Trauer) mit strafender Person als CS.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 30px;\"><strong>Konsequenzen f\u00fcr P\u00e4dagogik, F\u00fchrung u. Kommunikation<\/strong>:<\/p>\n<p style=\"padding-left: 30px;\">Wenn Bestrafung zur Verhaltenskontrolle eingesetzt wird, dann:<\/p>\n<blockquote>\n<ul>\n<li>kurze Dauer der Bestrafung<\/li>\n<li>geringe Intensit\u00e4t (Vermeidung klassisch konditionierter aversiver Emotionen mit Erziehungsperson als CS<\/li>\n<li>keine k\u00f6rperliche Z\u00fcchtigung (Vermeidung klassisch konditionierter aversiver Emotionen mit Erziehungsperson als CS)<\/li>\n<li>sollte auf Situation beschr\u00e4nkt bleiben, in der das unerw\u00fcnschte Verhalten auftritt (diskriminative Hinweisreize beachten)<\/li>\n<li>unmittelbare Kontingenz beachten (nicht: \u201eWarte bis Papa nach Hause kommt.\u201c)<strong><\/strong><strong><\/strong><\/li>\n<li><strong>Wichtig<\/strong>: Aufzeigen leicht durchf\u00fchrbarer Verhaltensalternativen, die mit positiver Verst\u00e4rkung einher gehen (vgl. <a title=\"Konstruktives Feedback\" href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/konstruktives-feedback\" target=\"_blank\">konstruktives Feedback<\/a>)<strong>.<\/strong><\/li>\n<\/ul>\n<\/blockquote>\n<ul>\n<li><em>Modelllernen<\/em> (Bandura 1977)<\/li>\n<\/ul>\n<p style=\"padding-left: 60px;\">Leitgedanke:<\/p>\n<p style=\"padding-left: 60px;\">Erfahrungen \u00fcber Verhaltens-Verst\u00e4rkungskontingenzen braucht nicht jeder Mensch pers\u00f6nlich zu machen, sondern kann sie <strong>per Beobachtung <\/strong>sammeln und der Steuerung seines eigenen Verhaltens zugrunde legen.<\/p>\n<p style=\"padding-left: 60px;\">Definition:<br \/>\nBeobachtungslernen beschreibt den Erwerb oder die Ver\u00e4nderung von Verhaltensweisen durch Beobachtung eines <strong>sozialen Modells <\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0 (Vorbildes), welches entweder real oder symbolisch, beispielsweise durch Film, Fernsehen, Text etc. gegeben sein kann.<\/p>\n<p style=\"padding-left: 60px;\">\u00a0Modelllernen ist <strong>am erfolgreichsten<\/strong>, wenn:<\/p>\n<blockquote>\n<ul>\n<li>beobachtet wird, dass das Modell f\u00fcr sein Verhalten verst\u00e4rkt wird.<\/li>\n<li>das Modell als positiv wahrgenommen wird (z.B. wenn es beliebt erscheint, \u00fcber Macht verf\u00fcgt, respektiert wird).<\/li>\n<li>der Beobachter \u00c4hnlichkeiten zwischen sich und dem Modell wahrnimmt (z.B. Modell hat \u00e4hnliche Hobbies, F\u00e4higkeiten, Beruf).<\/li>\n<li>das Verhalten des Modells sichtbar und auff\u00e4llig ist (Figur-Grund Gliederung).<\/li>\n<li>die Kompetenz des Beobachters ausreicht, das Modellverhalten nachzuahmen (Handlungen k\u00f6nnen neu sein, m\u00fcssen aber in ihrer Komplexit\u00e4t dem jeweiligen Entwicklungsstand angepasst sein.)<\/li>\n<\/ul>\n<\/blockquote>\n<p style=\"padding-left: 30px;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"padding-left: 60px;\"><strong>Konsequenz f\u00fcr Erziehungs- und F\u00fchrungsverhalten<\/strong>:<br \/>\nSich des eigenen Modellverhaltens bewusst sein und sich dementsprechend verhalten: \u201eLive what you preach.\u201c<\/p>\n<ul style=\"padding-left: 30px;\">\n<li><em>Erregungs\u00fcbertragung<\/em> (Zillmann 1978)<\/li>\n<\/ul>\n<p style=\"padding-left: 60px;\">\u00a0Grundlage:<br \/>\nErh\u00f6hte physiologische Erregung (engl. \u201earousal\u201c &#8211; z.B. k\u00f6rperliche Ersch\u00f6pfung, Hunger, Durst etc.) kann aggressive Reaktionen (egal welcher Ursache) verst\u00e4rken.<\/p>\n<ul>\n<li><em>Theorie der Errungs\u00fcbertragung<\/em> (Excitation-Transfer):<\/li>\n<\/ul>\n<p style=\"padding-left: 60px;\">Die Theorie geht davon aus, dass erh\u00f6hte Erregung die Aggressionsbereitschaft steigert, auch in Situationen, die nicht Ursache der Erregung sind. Dabei kann eine Resterregung aus fr\u00fcheren Situationen zur Erregung aus der aktuellen Situation additiv hinzukommen.<\/p>\n<p style=\"padding-left: 60px;\">Je unklarer die Ursache f\u00fcr die k\u00f6rperliche Erregung, desto st\u00e4rker der Effekt der Erregungs\u00fcbertragung.<\/p>\n<ul style=\"padding-left: 30px;\">\n<li><em>Kognitiv-Neoassoziationistisches Modell<\/em> (Berkowitz 1993)<\/li>\n<\/ul>\n<p style=\"padding-left: 60px;\">Grundlagen:<br \/>\nTheoretisches Modell, dass den Zusammenhang zwischen <strong>negativem Affekt <\/strong>und <strong>aggressivem Verhalten <\/strong>beschreibt.<\/p>\n<p style=\"padding-left: 60px;\">Es werden insbesondere <strong>Ged\u00e4chtnis- und Bewertungsprozesse <\/strong>ber\u00fccksichtigt. Demnach kann ein negativer Affekt zu zwei m\u00f6glichen Ged\u00e4chtnissystemen f\u00fchren, die wiederum eine spezifische Reaktion zur Folge haben (\u201efight or flight\u201c).<\/p>\n<p style=\"padding-left: 60px;\">Einfache Assoziationen sind entscheidend f\u00fcr die Art der Reaktion.<\/p>\n<p style=\"padding-left: 30px;\">\u00a0<a href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Kognitiv-Neoassoziationistisches-Modell.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-783\" title=\"hahnzog_organisationsberatung_Kognitiv-Neoassoziationistisches-Modell\" alt=\"\" src=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Kognitiv-Neoassoziationistisches-Modell-400x192.jpg\" width=\"400\" height=\"192\" srcset=\"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Kognitiv-Neoassoziationistisches-Modell-400x192.jpg 400w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Kognitiv-Neoassoziationistisches-Modell-150x72.jpg 150w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Kognitiv-Neoassoziationistisches-Modell.jpg 798w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p style=\"padding-left: 60px;\">\u00a0Nicht\u00a0 die Situation an sich, sondern erst die Assoziationen und Kognitionen f\u00fchren zu Aggression!<\/p>\n<p style=\"padding-left: 60px;\">\u00a0<strong>Kritik<\/strong>: Dritte basale Angstreaktion (\u201efreeze\u201c) wird nicht ber\u00fccksichtigt.<\/p>\n<h4>\u00a0d) Personale Bedingungen:<\/h4>\n<ul>\n<li><strong>\u00a0Aggression als trait (stabiles Pers\u00f6nlichkeitsmerkmal)<\/strong>:<br \/>\nZeitliche Stabilit\u00e4t vergleichbar mit der von Intelligenzwerten. Dadurch ist bei sehr hohen und sehr niedrigen Werten zuk\u00fcnftiges aggressives Verhalten relativ gut vorhersagbar.<\/li>\n<\/ul>\n<ul>\n<li><strong>Feindselige Attributionsstile<\/strong>:<br \/>\nTendenz, mehrdeutiges Verhalten anderer Personen als Ausdruck feindseliger Absicht zu interpretieren. \u00e0 \u201eculture of honour\u201c<\/li>\n<\/ul>\n<ul>\n<li><strong>Geschlechterunterschiede<\/strong>:<br \/>\nKriminalstatistiken belegen ein einen starken M\u00e4nner\u00fcberhang bei Gewaltverbrechen. Die St\u00e4rke des Geschlechtseffekts ist jedoch von mittlerer Gr\u00f6\u00dfenordnung und zudem f\u00fcr verbale Aggression geringer als f\u00fcr k\u00f6rperliche.<\/li>\n<\/ul>\n<h4>e) situative Bedingungen:<\/h4>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Alkohol<\/strong>:<br \/>\nSpielt eine wichtige Rolle bei Gewaltverbrechen, insbesondere Mord, h\u00e4uslicher Gewalt, sexuellem Missbrauch, sexueller Gewalt, Partnergewalt und intergruppaler Gewalt (aggressionsf\u00f6rdernde Wirkung auch bei anderen psychogenen Substanzen, u.a. Koffein!).<br \/>\nAllerdings starke intraindividuelle Unterschiede (\u00e0 Pers\u00f6nlichkeitsfaktoren).<\/li>\n<\/ul>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Temperatur<\/strong>: <strong>Hitzehypothese<\/strong> (Anderson et al. 2000):<br \/>\nGewaltverbrechen im Sommer h\u00e4ufiger als im Winter. Jedoch Einfluss des unterschiedlichen Sozialverhaltens.<\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">In Laborexperimenten lie\u00dfen sich keine eindeutigen Ergebnisse belegen:<br \/>\nAnstieg von aggressivem Verhalten bei steigender Temperatur (u.a. auch bei Schw\u00fcle, Schmerz, Gestank), jedoch sinkt die Aggressionstendenz ab 30\u00b0 C wieder.<\/p>\n<h4>f)\u00a0\u00a0\u00a0 Mediale Gewaltdarstellung:<\/h4>\n<p>Empirische Untersuchungen (Labor-, L\u00e4ngsschnitt-, Korrelationsstudien) belegen, dass die Wahrscheinlichkeit aggressiven und gewaltsamen Verhaltens durch Gewalt in den Medien sowohl kurz- als auch langfristig erh\u00f6ht wird.<\/p>\n<p>Jedoch sind die Effektst\u00e4rken ziemlich gering.<\/p>\n<p>Wirkung:<\/p>\n<ul>\n<li><em>Accessibility<\/em>: Leichtigkeit f\u00fcr den Zugriff auf aggressive Muster erh\u00f6ht.<\/li>\n<li><em>Soziale Lernprozesse<\/em>: Gro\u00dfteil der dargestellten aggressiven Verhaltensweisen wird belohnt oder bleibt unbestraft.<\/li>\n<li><em>Habituation<\/em>: Mitgef\u00fchl mit den Leiden von Gewaltopfern wird durch langfristigen medialen Gewaltkonsum verringert.<\/li>\n<li>Entwicklung eines <em>feindseligen Attributionsstils<\/em> bei mehrdeutigen Situationen wird gef\u00f6rdert.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong>2. Prosoziales Verhalten<\/strong><\/h2>\n<p>Definitionen<\/p>\n<p style=\"padding-left: 30px;\">\u00a0<a href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Prosoziales-Verhalten.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-784\" title=\"hahnzog_organisationsberatung_Prosoziales Verhalten\" alt=\"\" src=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Prosoziales-Verhalten-221x300.jpg\" width=\"221\" height=\"300\" srcset=\"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Prosoziales-Verhalten-221x300.jpg 221w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Prosoziales-Verhalten-73x100.jpg 73w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Prosoziales-Verhalten.jpg 342w\" sizes=\"auto, (max-width: 221px) 100vw, 221px\" \/><\/a><\/p>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Helfen<\/strong>:<br \/>\nHandlungen, die die Absicht verfolgen, die Situation des Hilfeempf\u00e4ngers zu verbessern.<\/li>\n<li><strong>Prosoziales Verhalten<\/strong>:<br \/>\nHilfeverhalten, das nicht durch berufliche oder private Verpflichtungen motiviert ist und nicht von einer Organisation ausgef\u00fchrt wird. Begrenzte Ausnahmen: Wohlt\u00e4tigkeitsorganisationen.<\/li>\n<li><strong>Altruismus<\/strong>:<br \/>\nProsoziales Verhalte, dessen oberstes Ziel darin besteht, einer anderen Person zu n\u00fctzen, und pers\u00f6nliche Ziele nachrangig sind.<\/li>\n<\/ul>\n<h4>Sozialer Einfluss:<\/h4>\n<p><strong>Variablen der sozialen Situation <\/strong>haben den gr\u00f6\u00dften Einfluss darauf prosoziales Verhalten zu behindern oder zu verhindern:<\/p>\n<ul style=\"padding-left: 30px;\">\n<li><em>Effekt der Anzahl (Verantwortungsdiffusion) <\/em>(Darley &amp; Latan\u00e9 1968):<br \/>\nEinfluss der Gruppengr\u00f6\u00dfe auf das Hilfeverhalten: Je gr\u00f6\u00dfer die Anzahl der Gruppenmitglieder, desto geringer Wahrscheinlichkeit daf\u00fcr.<span style=\"text-decoration: underline;\"><br \/>\nHintergrund<\/span>: Jeder Einzelne glaubt, dass nicht die ganze Verantwortung alleine auf ihm lastet \u2013 er \u201eteilt\u201c diese mit den anderen Zeugen.<\/li>\n<\/ul>\n<ul style=\"padding-left: 30px;\">\n<li>\u201e<em>Nothing has happend<\/em>\u201c:<br \/>\n<em>Implizite Modellierung <\/em>durch das Verhalten der anderen Zeugen: Die Zeugen sind sich gegenseitig Modell f\u00fcr Passivit\u00e4t, \u201eNichts-Tun\u201c wird zu einer sozialen Norm (<em>Pluralitische Ignoranz<\/em>)<\/li>\n<\/ul>\n<ul style=\"padding-left: 30px;\">\n<li><em>\u201eFear of embarrassment\u201c<\/em>:<br \/>\nAus Angst, sich zu blamieren, entsteht Verlegenheit. Dies spielt insbesondere dann, wenn die Zweifel daran erfolgreich zu sein hoch \u00a0\u00a0\u00a0\u00a0\u00a0 sind.\u00a0 Der gleiche Effekt tritt ein, wenn die Situation irrt\u00fcmlich als gef\u00e4hrlich eingesch\u00e4tzt werden k\u00f6nnte (<em>Bewertungsangst<\/em>).<\/li>\n<\/ul>\n<ul style=\"padding-left: 30px;\">\n<li><em>Eile<\/em>:<br \/>\nJe st\u00e4rker potenzielle Helfer unter Zeitdruck stehen, desto geringer ist die Wahrscheinlichkeit, dass sie helfen.<\/li>\n<\/ul>\n<p>Hilfeverhalten im Notfall: <strong>Rahmenmodell des Hilfeverhaltens <\/strong>(Darley &amp; Latan\u00e9 1968):<\/p>\n<p style=\"padding-left: 30px;\">a)\u00a0\u00a0\u00a0<em> Erkenne die Situation<\/em><\/p>\n<p style=\"padding-left: 30px;\">b)\u00a0\u00a0<em>\u00a0 Interpretiere die Situation als Notsituation<\/em><\/p>\n<p style=\"padding-left: 30px;\">Hilfsbed\u00fcrftigkeit muss eindeutig signalisiert sein und auch Kontextreize\u00a0 m\u00fcssen f\u00fcr Notsituation sprechen vgl. Attributionsprozesse!<\/p>\n<p style=\"padding-left: 30px;\">\u00a0Problem: Pluralistische Ignoranz:<br \/>\n\u201eDie anderen helfen nicht, also gibt es auch keine Notsituation.\u201c<\/p>\n<p style=\"padding-left: 30px;\">c)\u00a0\u00a0\u00a0 <em>\u00dcbernehme pers\u00f6nliche Verantwortung<\/em><\/p>\n<p style=\"padding-left: 30px;\">Problem: <em>Verantwortungsdiffusion<\/em><\/p>\n<p style=\"padding-left: 30px;\"><em><\/em>d)\u00a0\u00a0\u00a0 <em>W\u00e4hle einen Weg, um zu helfen<\/em><\/p>\n<p style=\"padding-left: 30px;\">e)\u00a0\u00a0\u00a0 F\u00fchre die Entscheidung aus!<\/p>\n<p style=\"padding-left: 30px;\">Voraussetzung: M\u00f6glichkeit und F\u00e4higkeit zur Hilfeleistung.<\/p>\n<p style=\"padding-left: 30px;\">Nur wenn alle f\u00fcnf Stufen erfolgreich absolviert werden, kommt es zu Hilfeverhalten.<\/p>\n<p style=\"padding-left: 30px;\">\u00a0Weitere Einflussvariablen: Kosten-Nutzen-Rechnung, Gerechte-Welt-Ph\u00e4nomen, Einfluss von Stereotypen etc.<\/p>\n<h4><strong>Entstehung<\/strong> von prosozialem Verhalten<\/h4>\n<p style=\"padding-left: 30px;\">\u00a0a)\u00a0\u00a0\u00a0 <em>Der evolution\u00e4re\/soziobiologische Ansatz<\/em>:<\/p>\n<p style=\"padding-left: 30px;\">Prosoziales Verhalten gegen\u00fcber Verwandten (Tr\u00e4ger \u00e4hnlicher Genkombinationen) erh\u00f6ht eine erfolgreiche Verteilung der eigenen Gene in die n\u00e4chste Generation. Die Bereitschaft zur Hilfeleistung steigt mit dem Grad der Verwandtschaft.<\/p>\n<p style=\"padding-left: 30px;\">\u00a0Problem: Keine interindividuellen und kontextabh\u00e4ngigen Unterschiede.<\/p>\n<p style=\"padding-left: 30px;\"><em>\u00a0<\/em><\/p>\n<p style=\"padding-left: 30px;\"><em>b)\u00a0\u00a0\u00a0 <\/em><em>Reziproker Altruismus<br \/>\n<\/em>Hintergrund: Prosoziales Verhalten erh\u00f6ht die eigene \u00dcberlebenschance. Nutzen der geleisteten Hilfe: Chance, selbst Hilfe zu erhalten, ist erh\u00f6ht.<\/p>\n<p style=\"padding-left: 30px;\"><em><\/em>Bedingungen: Vertrauen, Stabilit\u00e4t in die Gruppenmitgliedschaft, Dauerhaftigkeit der Gruppe, hohe gruppeninterne Wiedererkennbarkeit.<\/p>\n<p style=\"padding-left: 30px;\">Kulturunabh\u00e4ngige Reziprozit\u00e4tsnormen:<br \/>\nMenschen sollen denen helfen, die ihnen geholfen haben.<br \/>\nMenschen sollen die nicht verletzen, die ihnen geholfen haben.<\/p>\n<p style=\"padding-left: 30px;\">c)\u00a0\u00a0\u00a0 <em>Der individualistische Ansatz<\/em>:<\/p>\n<p style=\"padding-left: 30px;\">Hilfreiches Verhalten wird weniger durch genetische Bedingungen, sondern eher durch soziales Lernen erworben.<\/p>\n<p style=\"padding-left: 30px;\"><em><br \/>\n<\/em><\/p>\n<p style=\"padding-left: 30px;\"><em>Effekte der Emotion<\/em>:<br \/>\nIm Allgemeinen f\u00f6rdert <em>positive Stimmung <\/em>die Bereitschaft zur Hilfeleistung. Die Auswirkungen der positiven Stimmung sind zeitlich nur sehr begrenzt jedoch st\u00e4rker und best\u00e4ndiger als die Effekte negativer Stimmung.<\/p>\n<p style=\"padding-left: 30px;\">Auch <em>negative Affekte <\/em>k\u00f6nnen prosoziales Verhalten hervorrufen:<br \/>\nInterpersonelle Schuld (empfundene Verantwortung f\u00fcr das Leiden eines anderen) erh\u00f6ht prosoziales Verhalten und tr\u00e4gt in der Regel dazu bei, dass pers\u00f6nliche Beziehungen aufrecht erhalten werden.<\/p>\n<p style=\"padding-left: 30px;\">Zudem: Das Leid anderer erzeugt negative Gef\u00fchle, diese werden durch Hilfeleistung verringert.<\/p>\n<p style=\"padding-left: 30px;\">\u00a0Allerdings: Traurigkeit senkt die Bereitschaft zur Hilfeleistung.<\/p>\n<p style=\"padding-left: 30px;\"><em>Pers\u00f6nlichkeitsfaktoren<\/em>, die prosoziales Verhalten vor allem bedingen:<\/p>\n<ul>\n<li>\u00a0Empathie<\/li>\n<li>\u00a0soziale Verantwortung<\/li>\n<li>\u00a0internale Kontroll\u00fcberzeugung<\/li>\n<li>\u00a0Glaube an eine gerechte Welt<\/li>\n<li>\u00a0positives Selbstwergef\u00fchl<\/li>\n<\/ul>\n<h4>Besondere Perspektiven von Hilfeverhalten:<\/h4>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Kompetitiver Altruismus<\/strong>:<br \/>\nSich gegenseitig an Altruismus in der \u00d6ffentlichkeit \u00fcbertreffen, um in der Rangliste h\u00f6her zu steigen und selbst besseren Zugang zu Ressourcen zu bekommen.<\/li>\n<\/ul>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Konsequenzen von Hilfe:<br \/>\n<\/strong>Hilfe erhalten wird nicht immer positive wahrgenommen. Wenn Hilfe nicht ben\u00f6tigt wird oder der Selbstwert unter der Zuhilfenahme von Unterst\u00fctzung verringert wird, kann implizieren, dass der Hilfeempf\u00e4nger schwach und bed\u00fcrftig ist.<\/li>\n<\/ul>\n<h4>Voraussetzung f\u00fcr erfolgreiche Hilfeleistung:<\/h4>\n<ul style=\"padding-left: 30px;\">\n<li>Reduktion von Ambiguit\u00e4t (\u201eIch brauche jetzt Hilfe.\u201c)<\/li>\n<li>konkrete Verantwortlichkeit herstellen (\u201eIch brauche deine Hilfe.\u201c)<\/li>\n<li>Identifikation mit Hilfsbed\u00fcrftigem f\u00f6rdern (\u201eVersetz dich in meine Lage.\u201c)<\/li>\n<li>Aktivierung von Normen<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>3. Interpersonale Attraktion und intime Beziehungen<\/h2>\n<p>Grundlagen:<\/p>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Affiliation<\/strong>:<br \/>\nDie Tendenz, die Gesellschaft anderer Menschen zu suchen,\u00a0 selbst wenn wir uns ihnen nicht besonders nahe f\u00fchlen.<\/li>\n<\/ul>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Attraktivit\u00e4t<\/strong> \u2013 Zwischenmenschliche Anziehung:<br \/>\nPositive Gef\u00fchle gegen\u00fcber einer anderen Person einschlie\u00dflich der Tendenz, die Gegenwart des anderen zu suchen.<\/li>\n<\/ul>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Bindungstheorie<\/strong> (John Bowlby, 1969):<br \/>\nAffiliation ist eine angeborene Verhaltenstendenz, die dazu f\u00fchrt, dass Neugeborene bei Gefahrensituationen engen Kontakt zu ihrer Mutter suchen und so eine enge Beziehung aufbauen. Durch Verhaltensweisen wie L\u00e4cheln und Schreien erh\u00f6hen sie ihre \u00dcberlebenschancen.<\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">Je sicherer diese Bindungserfahrung, desto stabiler die Grundlage f\u00fcr intime Beziehungen im Erwachsenenalter<\/p>\n<h4>Theorie des sozialen Vergleichs (Festinger):<\/h4>\n<p>Hypothese:<\/p>\n<p style=\"padding-left: 30px;\">Menschen suchen den Kontakt zu den Personen, mit denen sie sich am besten vergleichen k\u00f6nnen, um Informationen \u00fcber ihre eigenen Emotionen und\u00a0 ihr effektivstes Verhalten zu erhalten.<\/p>\n<p>Insbesondere folgende Grundannahmen bedingen soziale Vergleiche:<\/p>\n<ul style=\"padding-left: 30px;\">\n<li>Menschen haben das Bed\u00fcrfnis, sich ein realistisches Bild von der Welt zu machen \u2013 die eigene Pers\u00f6nlichkeit eingeschlossen.<\/li>\n<li>Wenn objektive Vergleiche nicht m\u00f6glich sind, findet sozialer Vergleich statt.<\/li>\n<li>Ein Grundmotiv des Menschen ist es, seine F\u00e4higkeiten und Fertigkeiten zu verbessern.<\/li>\n<li>Personen mit \u00e4hnlichen Eigenschaften\/Hintergrund bieten die meisten Informationen f\u00fcr soziale Vergleiche (Peer comparison).<\/li>\n<li>Menschen sind motiviert Einstellungsdissonanzen zu anderen zu reduzieren.<\/li>\n<\/ul>\n<h4>Soziale Unterst\u00fctzung \u2013 vier Komponenten (House 1981):<\/h4>\n<p>Attraktivit\u00e4t erf\u00fcllt unter anderem den Zweck, soziale Unterst\u00fctzung einfacher und erfolgreicher zu erhalten. Hierbei kann die Art der Unterst\u00fctzung in vier verschiedenen Komponenten differenziert werden:<\/p>\n<ul style=\"padding-left: 30px;\">\n<li><span style=\"text-decoration: underline;\">Emotionale<\/span> Unterst\u00fctzung (sich umsorgt, geliebt und gesch\u00e4tzt f\u00fchlen)<\/li>\n<li><span style=\"text-decoration: underline;\">Einsch\u00e4tzung<\/span>sunterst\u00fctzung (R\u00fcckmeldung, wie man Objekte bewertet)<\/li>\n<li><span style=\"text-decoration: underline;\">Informationale<\/span> Unterst\u00fctzung (Informationen zu Objekten erhalten)<\/li>\n<li><span style=\"text-decoration: underline;\">Instrumentelle<\/span> Unterst\u00fctzung (konkrete Hilfe erhalten)<\/li>\n<\/ul>\n<h4><strong>Einsamkeit:<\/strong><\/h4>\n<p>Affektive Reaktion auf das subjektiv empfundene Defizit von Anzahl und Art sozialer Beziehungen. Es werden differenziert (Weiss 1975):<\/p>\n<ul style=\"padding-left: 30px;\">\n<li>Nichtvorhandensein eines vertrauten Partners\u2192 <span style=\"text-decoration: underline;\">emotionale Einsamkeit<\/span><\/li>\n<li>Nichtvorhandensein unterst\u00fctzender Freunde sowie fehlende Einbettung \u00a0ein soziales Netz \u2192 <span style=\"text-decoration: underline;\">soziale Einsamkeit<\/span><\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">Emotionale Einsamkeit kann kaum durch Freunde oder soziale Netzwerke kompensiert werden (vgl. Bindungstheorie).<\/p>\n<p style=\"padding-left: 30px;\">\u00a0Epidemiologische Untersuchungen belegen: Erh\u00f6hte Sterblichkeit im Alter bei sozialer Einsamkeit (insbes. M\u00e4nner).<\/p>\n<h4><strong>\u00a0Entstehung von Freundschaften &#8211; R\u00e4umliche Umwelt:<\/strong><\/h4>\n<p>R\u00e4umliche N\u00e4he erleichtert die Entstehung von Freundschaften (Festinger et al. 1950, Back et al. 2008):<\/p>\n<ul style=\"padding-left: 30px;\">\n<li>Weniger (r\u00e4umliche) H\u00fcrden f\u00fcr die Entwicklung einer Freundschaft.<\/li>\n<li>Gr\u00f6\u00dfere Wahrscheinlichkeit f\u00fcr mehr Informationen \u00fcber andere Personen.<\/li>\n<li>M\u00f6glichkeit gemeinsame Interessen und Einstellungen zu entdecken eher gegeben als bei r\u00e4umlicher Distanz.<\/li>\n<li>Mere-Exposure-Effekte \u00e0 Intensives Menschliches Zusammensein<\/li>\n<li>Nicht zuletzt:<br \/>\nJe mehr r\u00e4umliche N\u00e4he &#8211; auch bedingt durch Institutionen, Regionen, Veranstaltungen, die wiederum \u00e4hnliche Einstellungen erm\u00f6glichen &#8211; desto h\u00f6her die Wahrscheinlichkeit, sich zu begegnen.<\/li>\n<li>\u00c4hnlichkeit von Einstellungen:<\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">\u00c4hnlichkeit in Bezug auf Alter, Familienstand, Ethnie, Intelligenz und insbesondere in Bezug auf Einstellungen beg\u00fcnstigen Freundschaften.<\/p>\n<p>Heymans &amp; Wiersma (1905):<br \/>\nMenschen sind h\u00e4ufiger mit Partnern verheiratet, die \u00e4hnliche Einstellungen (z.B. in Bezug auf: Essen &amp; Trinken, Politik und Religion).<\/p>\n<p>Byrne (1971) \u2013 Attraktionsparadigma:<br \/>\nZwischenmenschliche Anziehung ist direkt proportional zu der \u00a0 \u00c4hnlichkeit der Einstellungen zwischen den Personen.<br \/>\nZentrale Wirkung: Klassische Konditionierung durch emotionale Reaktion \u00a0\u00a0\u00a0\u00a0\u00a0 auf Einstellungs\u00e4u\u00dferung.<\/p>\n<p>Neben Vertrautheit ist <strong>physische Attraktivit\u00e4t<\/strong> eine starke Determinante von Sympathie:<\/p>\n<ul style=\"padding-left: 30px;\">\n<li>\u201eWhat is beautiful is good\u201c-Stereotyp:<br \/>\nAttraktiven Personen werden bessere Eigenschaften zugeschrieben.<\/li>\n<li>Halo-Effekt: Attraktivit\u00e4t \u00fcberstrahlt andere Eigenschaften<\/li>\n<li>Self-fulfilling-prophecies<\/li>\n<li>Determinanten der physischen Attraktivit\u00e4t:<\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">Symmetrie<\/p>\n<blockquote>\n<ul>\n<li>\u201eBabyface\u201c-Stereotyp bei Frauen (Zebrowitz 1997):<\/li>\n<li>gro\u00dfe Augen, rundes Gesicht, schmale Nase und Kinn.<\/li>\n<li>Evolutionsbiologische Perspektive: Attraktiv sind solche Merkmale, die die<br \/>\nChance auf erfolgreiche Reproduktion erh\u00f6hen<\/li>\n<li>\u00dcbereinstimmung mit aktuellen Normen der Attraktivit\u00e4t<\/li>\n<\/ul>\n<\/blockquote>\n<h4><strong>\u00a0Komponenten einer Liebesbeziehung (Sternberg 1988):<\/strong><\/h4>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Intimit\u00e4t: <\/strong>Vertrauen, N\u00e4he, Verbundenheit, W\u00e4rme und Selbst\u00f6ffnung<\/li>\n<li><strong>Leidenschaft: <\/strong>Physische Erregung, sexuelle Anziehung, starke Gef\u00fchle<\/li>\n<li><strong>Bindung: <\/strong>Kurzzeitig: Entscheidung, eine Person zu lieben Langfristig: Bindung, Aufrechterhaltung<\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">\u00a0<a href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Dreiecksmodell-der-Liebe.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-785\" title=\"hahnzog_organisationsberatung_Dreikomponentenmodell der Liebe\" alt=\"\" src=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Dreiecksmodell-der-Liebe-347x300.jpg\" width=\"347\" height=\"300\" srcset=\"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Dreiecksmodell-der-Liebe-347x300.jpg 347w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Dreiecksmodell-der-Liebe-115x100.jpg 115w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Dreiecksmodell-der-Liebe.jpg 555w\" sizes=\"auto, (max-width: 347px) 100vw, 347px\" \/><\/a><\/p>\n<p>Arten von Liebe nach der Dreieckstheorie (Sternberg 1988):<\/p>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Nicht-Liebe<\/strong>: Weder Intimit\u00e4t noch Leidenschaft noch Bindung<\/li>\n<li><strong>M\u00f6gen<\/strong>: Starke Vertrautheit, aber geringe Leidenschaft und Bindung<\/li>\n<li><strong>Romantische Liebe<\/strong>: Intimit\u00e4t u. Leidenschaft, geringe Bindung (\u00e0 Flirt)<\/li>\n<li><strong>Vernarrtheit<\/strong>: Starke Leidenschaft, aber geringe Intimit\u00e4t und Bindung<\/li>\n<li><strong>Alberne Liebe<\/strong>: Leidenschaft und Bindung, jedoch geringe Vertrautheit<\/li>\n<li><strong>Leere Liebe<\/strong>: Intensive Bindung, geringe Leidenschaft und Vertrautheit<\/li>\n<li><strong>Kumpelhafte Liebe<\/strong>: Vertrautheit und Bindung, geringe Leidenschaft<\/li>\n<li><strong>Vollendete \/ Vollkommene Liebe <\/strong><\/li>\n<\/ul>\n<p>Bindungsstile nach Bartholomew &amp; Horowitz (1991):<\/p>\n<p style=\"padding-left: 30px;\">\u00a0<a href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Bindungsstile.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-786\" title=\"hahnzog_organisationsberatung_Bindungsstile\" alt=\"\" src=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Bindungsstile-400x134.jpg\" width=\"400\" height=\"134\" srcset=\"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Bindungsstile-400x134.jpg 400w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Bindungsstile-150x50.jpg 150w, https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Bindungsstile.jpg 913w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p style=\"padding-left: 30px;\">\u00a0 Personen mit sicherem Bindungsstil:<\/p>\n<p style=\"padding-left: 30px;\">sind weniger eifers\u00fcchtig; k\u00f6nnen leichter um Unterst\u00fctzung bitten; haben weniger Angst, verlassen zu werden; neigen dazu Partnern st\u00e4rker zu vertrauen; haben stabilere und befriedigende Beziehungen.<\/p>\n<p style=\"padding-left: 30px;\"><strong>\u00a0<\/strong><\/p>\n<h4>Festlegung (Commitment) auf einen Partner:<\/h4>\n<p>Folgende Faktoren erh\u00f6hen die subjektiv empfundene Zufriedenheit der Partner in einer Liebesbeziehung &#8211; Investment-Modell (Rusbult &amp; Buunk, 1993):<\/p>\n<ul style=\"padding-left: 30px;\">\n<li><strong>Hohe Zufriedenheit<\/strong>:<br \/>\nHohe Ertr\u00e4ge aus Partnerschaft, erh\u00f6hen Zufriedenheit und Festlegung<\/li>\n<li><strong>Geringe Qualit\u00e4t der Alternativen<\/strong>:<br \/>\nGeringe Chancen auf bessere Alternativen (alternative Partner, Alleinleben, Substitution durch Freunde, Beruf etc.) erh\u00f6hen Festlegung.<\/li>\n<li><strong>H\u00f6he der Investitionen<\/strong>:<br \/>\nJe h\u00f6her die Investition (Zeit und Energie, Opfer bringen, Freundeskreis aufbauen, gemeinsame Erinnerungen, Hobbies, Besitzt\u00fcmer) in die Partnerschaft, desto h\u00f6her die Festlegung.<\/li>\n<\/ul>\n<h4>\u00a0Trennen \u2013 Verlassen \u2013 Scheidung:<\/h4>\n<p><strong>Risikofaktoren<\/strong>, die eine Trennung\/Scheidung beg\u00fcnstigen:<\/p>\n<ul style=\"padding-left: 30px;\">\n<li>Junge Paare, die zum ersten Mal heiraten<\/li>\n<li>\u201eEgocentric-Bias\u201c: Eigenes Verhalten ist sowohl Grund als auch Ziel de Verhaltens des Partners<\/li>\n<li>Nach den ersten f\u00fcnf Jahren einer Ehe nimmt das Risiko einer Scheidung signifikant ab.<\/li>\n<li>Kinder<\/li>\n<li>Mangelnde Konfliktbew\u00e4ltigung und negative Kommunikation<\/li>\n<li>\u00dcbertragung von beruflichen Problemen auf die Partnerschaft<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Literatur<\/h2>\n<p>Lehrb\u00fccher:<\/p>\n<ul style=\"padding-left: 30px;\">\n<li>Aronson, E., Wilson, T.D. &amp; Akert, R.M. (2008). <em>Sozialpsychologie<\/em>. M\u00fcnchen: Pearson Studium.<\/li>\n<li>Baron, R. A., Branscombe, N. &amp; Byrne, D. (2008). <em>Social Psychology<\/em>. Boston: Pearson.<\/li>\n<li>Bierhoff, H.-W. &amp; Frey, D. (Hrsg.)(2006). <em>Handbuch der Sozialpsychologie und Kommunikationspsychologie<\/em>. G\u00f6ttingen: Hogrefe.<\/li>\n<li>Gerrig, R. &amp; Zimbardo, P. (2008). <em>Psychologie<\/em>. M\u00fcnchen: Pearson.<\/li>\n<li>Jonas, K., Stroebe, W. &amp; Hewstone, M. (Hrsg.) (2007). <em>Sozialpsychologie<\/em>. Heidelberg: Springer.<\/li>\n<li>Marmet, O. (2006). <em>Ich und du und so weiter. Kleine Einf\u00fchrung in die Sozialpsychologie<\/em>. Weinheim: Beltz.<\/li>\n<li>Werth, L. &amp; Mayer, J. (2008). <em>Sozialpsychologie<\/em>. Berlin: Spektrum.<\/li>\n<\/ul>\n<p style=\"padding-left: 30px;\">Weitere Quellen und Literatur erhalten Sie gerne auf Anfrage oder in unseren <a title=\"Literatur\" href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/literatur\">Literaturempfehlungen<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#top\" rel=\"nofollow\">Nach oben<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a title=\"Lexikon\" href=\"http:\/\/www.hahnzog.de\/organisationsberatung\/lexikon\">Zur\u00fcck zur \u00dcbersicht<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie k\u00f6nnen sich diesen Artikel zum Nachlesen und Weiterverarbeiten auch als PDF herunterladen: &nbsp; Prof. Dr. Simon Hahnzog: Sozialpsychologie &#8211; Soziale Interaktion herunterladen Zur\u00fcck zur \u00dcbersicht oder Artikel online lesen: &nbsp; Prof. Dr. Simon Hahnzog &#8211; Ausgew\u00e4hlte Aspekte der Sozialpsychologie:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[86,88,84,87,85],"class_list":["post-780","post","type-post","status-publish","format-standard","hentry","category-lexikon","tag-aggression","tag-altruismus","tag-freundschaft","tag-hilfe","tag-liebe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sozialpsychologie: Soziale Interaktion - hahnzog - organisationsberatung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sozialpsychologie: Soziale Interaktion - hahnzog - organisationsberatung\" \/>\n<meta property=\"og:description\" content=\"Sie k\u00f6nnen sich diesen Artikel zum Nachlesen und Weiterverarbeiten auch als PDF herunterladen: &nbsp; Prof. Dr. Simon Hahnzog: Sozialpsychologie &#8211; Soziale Interaktion herunterladen Zur\u00fcck zur \u00dcbersicht oder Artikel online lesen: &nbsp; Prof. Dr. Simon Hahnzog &#8211; Ausgew\u00e4hlte Aspekte der Sozialpsychologie:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion\" \/>\n<meta property=\"og:site_name\" content=\"hahnzog - organisationsberatung\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-27T09:54:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-14T10:52:08+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg\" \/>\n<meta name=\"author\" content=\"hahnzog_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"hahnzog_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion\"},\"author\":{\"name\":\"hahnzog_admin\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#\\\/schema\\\/person\\\/7db4c6f2973b01e5a1fe2f77c3b6fe2c\"},\"headline\":\"Sozialpsychologie: Soziale Interaktion\",\"datePublished\":\"2011-07-27T09:54:21+00:00\",\"dateModified\":\"2014-03-14T10:52:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion\"},\"wordCount\":2999,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg\",\"keywords\":[\"Aggression\",\"Altruismus\",\"Freundschaft\",\"Hilfe\",\"Liebe\"],\"articleSection\":[\"Lexikon\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion\",\"url\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion\",\"name\":\"Sozialpsychologie: Soziale Interaktion - hahnzog - organisationsberatung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg\",\"datePublished\":\"2011-07-27T09:54:21+00:00\",\"dateModified\":\"2014-03-14T10:52:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion#primaryimage\",\"url\":\"http:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg\",\"contentUrl\":\"http:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/sozialpsychologie-soziale-interaktion#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sozialpsychologie: Soziale Interaktion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#website\",\"url\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/\",\"name\":\"hahnzog - organisationsberatung\",\"description\":\"Gesunde Unternehmen gestalten\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#organization\",\"name\":\"hahnzog Organisationsberatung\",\"url\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Logo_Hahnzog.png\",\"contentUrl\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Logo_Hahnzog.png\",\"width\":286,\"height\":98,\"caption\":\"hahnzog Organisationsberatung\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hahnzog.de\\\/organisationsberatung\\\/#\\\/schema\\\/person\\\/7db4c6f2973b01e5a1fe2f77c3b6fe2c\",\"name\":\"hahnzog_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7153dc94e443f4e23082457f134b3b729ebad029aee7538cd1c476bc0d1b93e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7153dc94e443f4e23082457f134b3b729ebad029aee7538cd1c476bc0d1b93e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7153dc94e443f4e23082457f134b3b729ebad029aee7538cd1c476bc0d1b93e5?s=96&d=mm&r=g\",\"caption\":\"hahnzog_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sozialpsychologie: Soziale Interaktion - hahnzog - organisationsberatung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion","og_locale":"de_DE","og_type":"article","og_title":"Sozialpsychologie: Soziale Interaktion - hahnzog - organisationsberatung","og_description":"Sie k\u00f6nnen sich diesen Artikel zum Nachlesen und Weiterverarbeiten auch als PDF herunterladen: &nbsp; Prof. Dr. Simon Hahnzog: Sozialpsychologie &#8211; Soziale Interaktion herunterladen Zur\u00fcck zur \u00dcbersicht oder Artikel online lesen: &nbsp; Prof. Dr. Simon Hahnzog &#8211; Ausgew\u00e4hlte Aspekte der Sozialpsychologie:","og_url":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion","og_site_name":"hahnzog - organisationsberatung","article_published_time":"2011-07-27T09:54:21+00:00","article_modified_time":"2014-03-14T10:52:08+00:00","og_image":[{"url":"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg","type":"","width":"","height":""}],"author":"hahnzog_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"hahnzog_admin","Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion#article","isPartOf":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion"},"author":{"name":"hahnzog_admin","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#\/schema\/person\/7db4c6f2973b01e5a1fe2f77c3b6fe2c"},"headline":"Sozialpsychologie: Soziale Interaktion","datePublished":"2011-07-27T09:54:21+00:00","dateModified":"2014-03-14T10:52:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion"},"wordCount":2999,"publisher":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#organization"},"image":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion#primaryimage"},"thumbnailUrl":"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg","keywords":["Aggression","Altruismus","Freundschaft","Hilfe","Liebe"],"articleSection":["Lexikon"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion","url":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion","name":"Sozialpsychologie: Soziale Interaktion - hahnzog - organisationsberatung","isPartOf":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion#primaryimage"},"image":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion#primaryimage"},"thumbnailUrl":"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg","datePublished":"2011-07-27T09:54:21+00:00","dateModified":"2014-03-14T10:52:08+00:00","breadcrumb":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion#primaryimage","url":"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg","contentUrl":"http:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2011\/07\/hahnzog_organisationsberatung_Soziale-Interaktion_Titel_blau-141x100.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/sozialpsychologie-soziale-interaktion#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.hahnzog.de\/organisationsberatung\/"},{"@type":"ListItem","position":2,"name":"Sozialpsychologie: Soziale Interaktion"}]},{"@type":"WebSite","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#website","url":"https:\/\/www.hahnzog.de\/organisationsberatung\/","name":"hahnzog - organisationsberatung","description":"Gesunde Unternehmen gestalten","publisher":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hahnzog.de\/organisationsberatung\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#organization","name":"hahnzog Organisationsberatung","url":"https:\/\/www.hahnzog.de\/organisationsberatung\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#\/schema\/logo\/image\/","url":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2017\/07\/Logo_Hahnzog.png","contentUrl":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-content\/uploads\/2017\/07\/Logo_Hahnzog.png","width":286,"height":98,"caption":"hahnzog Organisationsberatung"},"image":{"@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hahnzog.de\/organisationsberatung\/#\/schema\/person\/7db4c6f2973b01e5a1fe2f77c3b6fe2c","name":"hahnzog_admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7153dc94e443f4e23082457f134b3b729ebad029aee7538cd1c476bc0d1b93e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7153dc94e443f4e23082457f134b3b729ebad029aee7538cd1c476bc0d1b93e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7153dc94e443f4e23082457f134b3b729ebad029aee7538cd1c476bc0d1b93e5?s=96&d=mm&r=g","caption":"hahnzog_admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/posts\/780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/comments?post=780"}],"version-history":[{"count":8,"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/posts\/780\/revisions"}],"predecessor-version":[{"id":2170,"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/posts\/780\/revisions\/2170"}],"wp:attachment":[{"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/media?parent=780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/categories?post=780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hahnzog.de\/organisationsberatung\/wp-json\/wp\/v2\/tags?post=780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}